{"id":233463,"date":"2022-02-16T08:25:41","date_gmt":"2022-02-16T08:25:41","guid":{"rendered":"https:\/\/www.swissbionic.com\/imrs-prime-system\/"},"modified":"2026-07-07T08:17:19","modified_gmt":"2026-07-07T08:17:19","slug":"imrs-prime-sistemi","status":"publish","type":"page","link":"https:\/\/recoveru.swissbionic.com\/it\/imrs-prime-sistemi\/","title":{"rendered":"iMRS prime Sistemi"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Section&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_color_gradient_start=&#8221;#ffffff&#8221; background_color_gradient_end=&#8221;#e5e5e5&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;center_right&#8221; custom_padding_tablet=&#8221;0px||0px||false|false&#8221; custom_padding_phone=&#8221;0px||0px||false|false&#8221; da_popup_slug=&#8221;exagon-applicators&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;50px||||false|false&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/logo_imrs_prime.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;iMRS prime&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_height=&#8221;120px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_line_height=&#8221;1.6em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>L\u2019unico e il solo sistema CEMP-6D per il benessere!<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-200px||||false|false&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code disabled_on=&#8221;on|on|off&#8221; module_class=&#8221;image_hotspot_imrs_prime&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]\t<div class=\"wrap_svl_center\">\r\n\t<div class=\"wrap_svl_center_box\">\r\n\t<div class=\"wrap_svl\" id=\"body_drag_234848\">\r\n\t\t<div class=\"images_wrap\">\r\n                            <img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrsprime-expert-set.png\" alt=\"\">\r\n            \t\t<\/div>\t\r\n\t\t \t\t \t\t <div class=\"drag_element tips \" style=\"top:45.58%;left:66.22%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Brain&lt;\/h4&gt;\n&lt;p&gt;Sincronizzatore delle onde cerebrali &#8211; Terapia olistica per il cervello umano!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-7&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:22.37%;left:50.55%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;iMRS prime Unit\u00e0 di controllo&lt;\/h4&gt;\n&lt;p&gt;Schermo LCD touch screen capacitivo da 10.2 pollici.&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-1&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n&lt;h4&gt;iMRS prime Strumenti Software&lt;\/h4&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#software-tools&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:27.38%;left:21%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Applicatore Spot&lt;\/h4&gt;\n&lt;p&gt;L\u2019applicatore specifico per trattare piccole aree del corpo&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-5&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:12.52%;left:28.56%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Applicatore Pad&lt;\/h4&gt;\n&lt;p&gt;L\u2019applicatore locale da utilizzare su aree specifiche del corpo!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-4&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:66.11%;left:43.78%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Sense&lt;\/h4&gt;\n&lt;p&gt;Tencologia Biofeedback&lt;br \/&gt;\nMonitora \u2013 Analizza \u2013 Valuta!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-8&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:67.45%;left:72%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Applicatore FIR&lt;\/h4&gt;\n&lt;p&gt;Il primo e unico applicatore-ibrido al mondo!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-3&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:44.24%;left:38.44%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;iMRS prime Connector Box&lt;\/h4&gt;\n&lt;p&gt;Elemento progettato come collegamento tra l\u2019unit\u00e0 di controllo iMRS prime e gli applicatori\/accessori.&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-2&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t \r\n\t\t  \t\t \t\r\n\t <\/div>\r\n\t <\/div>\r\n\t <\/div>\r\n\t[\/et_pb_code][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrsprime-expert-set.png&#8221; alt=&#8221;iMRS prime Expert Set&#8221; title_text=&#8221;iMRS prime Expert Set&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Control Panel&#8221; module_id=&#8221;section-1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; overflow-x=&#8221;hidden&#8221; da_popup_slug=&#8221;section-1&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_direction=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-control-unit.png&#8221; alt=&#8221;iMRS prime Control Unit&#8221; title_text=&#8221;iMRS prime Control Unit&#8221; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; animation_direction=&#8221;right&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Unit\u00e0 di controllo<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime\">\n<li>Struttura e piedistallo in alluminio spazzolato, ROHS\/REACH\/IP20.<\/li>\n<li>Schermo LCD touch screen capacitivo da 10.2 pollici.<\/li>\n<li>2 ingressi audio (3.5).<\/li>\n<li>2 ingressi USB.<\/li>\n<li>Cavo di collegamento (20-pin) alla Connector box.<\/li>\n<li>LED Indicatore di potenza.<\/li>\n<li>2 Altoparlanti integrati.<\/li>\n<li>Sensore NFC.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button1&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr1&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230489,230486,230483,230492,230495,230480&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Connector Box&#8221; module_id=&#8221;section-2&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; overflow-x=&#8221;hidden&#8221; da_popup_slug=&#8221;section-2&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-connectorbox.png&#8221; alt=&#8221;iMRS prime Connectorbox&#8221; title_text=&#8221;iMRS prime Connectorbox&#8221; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; sticky_limit_bottom=&#8221;row&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>iMRS prime Connector Box<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime dark-line\">\n<li>Elemento progettato come collegamento tra l\u2019unit\u00e0 di controllo iMRS prime e gli applicatori\/accessori.<\/li>\n<li>Microprocessore integrato con segnale multidirezionale.<\/li>\n<li>6 ingressi per accessori.<\/li>\n<li>2 ingressi per sensore bio-feedback.<\/li>\n<li>2 ingressi USB.<\/li>\n<li>2 Convertitori D\/A integrati che consentono l\u2019uso di due accessori individuali separati con una sola unit\u00e0 di controllo.<\/li>\n<li>Struttura in alluminio spazzolato per un\u2019efficace dissipazione del calore, ROHS\/REACH\/IP20.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button2&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr2&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr2&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230477,230474,230471&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Applicators&#8221; module_id=&#8221;exagon-applicators&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#20242B&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;rgba(32,36,43,0.54) 0%|rgba(32,36,43,0.55) 100%&#8221; background_color_gradient_start=&#8221;rgba(32,36,43,0.54)&#8221; background_color_gradient_end=&#8221;rgba(32,36,43,0.55)&#8221; background_image=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/bg_imrs_prime_01.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; da_popup_slug=&#8221;exagon-applicators&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Applicatori<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Row&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_direction=&#8221;bottom&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_series_label.png&#8221; alt=&#8221;Exagon Series&#8221; title_text=&#8221;Exagon Series&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_line_height=&#8221;1.6em&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>&#8220;Exagon Series&#8221; \u2013 la nuovissima generazione dei nostri applicatori. Ogni applicatore PEMF serve come conduttore dei segnali erogati al ricevitore ed \u00e8 quindi il componente pi\u00f9 importante. La nuovissima famiglia di applicatori Exagon unifica tutte le propriet\u00e0 vitali dei PEMF in un\u2019unica soluzione.<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime  dark-line\">\n<li>Il materiale selezionato \u00e8 biocompatible!<\/li>\n<li>L\u2019intero Sistema \u00e8 stato progettato per durare  anni anche con numerose applicazioni quotidiane!<\/li>\n<li>La struttura a nido d\u2019ape della superficie del tessuto \u00e8 traspirante, previene la sudorazione, la contaminazione ed \u00e8 facile da pulire! Le bobine di rame incorporate sono solide come la roccia e non isolate per creare la massima efficienza fisica della struttura del segnale elettromagnetico applicato! <\/li>\n<li>Le bobine di rame incorporate sono solide e non isolate per creare la massima efficienza fisica del campo elettromagnetico pulsato applicato!<\/li>\n<li>La \u201cFunzione di Controllo Ottico OFC\u201d di recente progettazione e costruzione, garantisce un monitoraggio costante della funzionalit\u00e0 di ogni applicatore e segnala malfunzionamenti con un LED rosso! Mostra anche gli spostamenti dei poli preprogrammati con colori diversi (blu e verde) durante l\u2019applicazione!<\/li>\n<li>Ogni applicatore Exagon dispone di intelligenza integrata al fine di garantire la comunicazione bilaterale con il processore principale del pannello di controllo iMRS prime!<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Mat&#8221; module_id=&#8221;section-3&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_popup_slug=&#8221;section-3&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_fir_label.png&#8221; alt=&#8221;Exagon FIR&#8221; title_text=&#8221;Exagon FIR&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;300px&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-exagon-fir.png&#8221; alt=&#8221;iMRS prime Exagon FIR Applicator&#8221; title_text=&#8221;iMRS prime Exagon FIR Applicator&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;]Il primo e unico applicatore-ibrido al mondo![\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime\">\n<li>6 bobine di rame solide come rocce, divise in tre coppie con diverse quantit\u00e0 di avvolgimenti per controllare l\u2019intensit\u00e0 del campo applicato su tutta la superficie.<\/li>\n<li>Forma d\u2019onda a triplo dente di sega per la massima efficienza del PEMF a bassa intensit\u00e0.<\/li>\n<li>Ripiegabile in 3 parti.<\/li>\n<li>Controllo di Funzionamento Operativo Integrato.<\/li>\n<li>Presa a scatto per uso medico.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;]<\/p>\n<p>\nL\u2019Exagon FIR rappresenta la pi\u00f9 avanzata tecnologia di applicazione PEMF ad oggi esistente. \u00c8 dotato di uno strato aggiuntivo isolato di uno specifico modello di filo in fibra di carbonio! La struttura del filo \u00e8 controllata dal pannello operativo dell\u2019iMRS prime per creare l\u2019esposizione e la temperatura definite delle lunghezze desiderate d\u2019infrosso lontano (approssimativamente tra 3 e 14 Micron). La tecnologia Exagon FIR insieme all\u2019iMRS prime apre un nuovo orizzonte completo nell\u2019applicazione combinata di onde elettromagnetiche a bassa intensit\u00e0  (PEMF e \u201cInfrarosso Lontano\u201d FIR simultaneamente) e l\u2019esperienza personale \u00e8 davvero unica nel suo genere:<\/p>\n<p><em><strong>Sembra letteralmente di galleggiare sopra un materassino in un lago calmo!<\/strong><\/em><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button3&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr3&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr3&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230511,230508&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Pad&#8221; module_id=&#8221;section-4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_popup_slug=&#8221;section-4&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_pad_label.png&#8221; alt=&#8221;Exagon Pad&#8221; title_text=&#8221;Exagon Pad&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;300px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-exagon-pad.png&#8221; alt=&#8221;iMRS prime Exagon Pad Applicator&#8221; title_text=&#8221;iMRS prime Exagon Pad Applicator&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]L\u2019applicatore locale da utilizzare su aree specifiche del corpo![\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime  dark-line\">\n<li>2 bobine robuste di rame solido per erogare l\u2019intensit\u00e0 del campo elettromagnetico in modo uniforme e controllato su tutta la superficie.<\/li>\n<li>Utilizzo dell\u2019onda quadra per una massima efficienza dei PEMF applicati localmente.<\/li>\n<li>Controllo di Funzionamento Operativo Integrato.<\/li>\n<li>Presa a scatto per uso medico.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button4&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr4&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230532,230535,230544,230547,230538,230553&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Spot&#8221; module_id=&#8221;section-5&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_popup_slug=&#8221;section-5&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_spot_label.png&#8221; alt=&#8221;Exagon Spot&#8221; title_text=&#8221;Exagon Spot&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;300px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-exagon-spot.png&#8221; alt=&#8221;iMRS prime Exagon Spot Applicator&#8221; title_text=&#8221;iMRS prime Exagon Spot Applicator&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]L\u2019applicatore specifico per trattare piccole aree del corpo[\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime\">\n<li>Applicatore di nuova concenzione e flessibile per un utilizzo localizzato che sfrutta \u201cl\u2019effetto-Helmholtz\u201d. <\/li>\n<li>1 bobina di rame solido inserita in ogni parte (2 in totale) per controllare in modo preciso l\u2019intensit\u00e0 del campo elettromagnetico erogato su una specifica area.<\/li>\n<li>Utilizzo dell\u2019onda quadra per una massima efficienza dei PEMF applicati localmente con l\u2019effetto-Helmholtz.<\/li>\n<li>Controllo funzionamento operativo integrato.<\/li>\n<li>Presa a scatto per uso medico.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button5&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr5&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr5&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230574,230577,230580,230598,230595,230592,230589,230583&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Spot&#8221; module_id=&#8221;section-7&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_popup_slug=&#8221;section-7&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_brain_label.png&#8221; alt=&#8221;Exagon Brain&#8221; title_text=&#8221;Exagon Brain&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;300px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-exagon-brain.png&#8221; alt=&#8221;iMRS prime Exagon Brain&#8221; title_text=&#8221;iMRS prime Exagon Brain&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]Sincronizzatore delle onde cerebrali &#8211; Terapia olistica per il cervello umano![\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime\">\n<li>Occhiali con 12 LED integrati su ogni lato. Posizionamento che oscura completamente l\u2019esterno per una prestazione ottimale.<\/li>\n<li>Emissione di onde luminose, colorate e sonore che stimolano il cervello combinate in un unico sistema. <\/li>\n<li>Banda elastica per regolazioni facili.<\/li>\n<li>Presa USB.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button7&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIyNDI4MCJ9fQ==@&#8221; button_text=&#8221;Learn more about Brainwave Entrainment&#8221; _builder_version=&#8221;4.17.0&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#22A2FF&#8221; button_border_width=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr7&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr7&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230502,230499,230505,230613,230616&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger7&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Pad&#8221; module_id=&#8221;section-8&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_popup_slug=&#8221;section-8&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_sense_label.png&#8221; alt=&#8221;Exagon Sense&#8221; title_text=&#8221;Exagon Sense&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;300px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-exagon-sense.png&#8221; alt=&#8221;iMRS prime Exagon Sense&#8221; title_text=&#8221;iMRS prime Exagon Sense&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]Tencologia Biofeedback: Monitora \u2013 Analizza \u2013 Valuta![\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime  dark-line\">\n<li>Sensore di fotopletismografia bifunzionale, di livello medico.<\/li>\n<li>Progettato per rilevare le variazioni di volume del sangue nel tessuto microvascolare.<\/li>\n<li>Valutazione SpO2 and HRV.<\/li>\n<li>Regolazione dinamica dell\u2019intensit\u00e0 durante un\u2019applicazione PEMF.<\/li>\n<li>Presa a scatto per uso medico.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#open-gallery&#8221; button_text=&#8221;Aprire la galleria&#8221; module_id=&#8221;galerie-button8&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIyNDQ0MyJ9fQ==@&#8221; button_text=&#8221;Learn more about Biofeedback&#8221; _builder_version=&#8221;4.17.0&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#22A2FF&#8221; button_border_width=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;galerie-mehr8&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; da_popup_slug=&#8221;galerie-mehr8&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;230559,230562,230565,230568&#8243; posts_number=&#8221;20&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;galerie-button-weniger8&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#22a2ff 0%|#603389 100%&#8221; background_color_gradient_start=&#8221;#22a2ff&#8221; background_color_gradient_end=&#8221;#603389&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; link_font=&#8221;|700|||||||&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"#close-gallery\">Chiudere la galleria<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Applicators&#8221; module_id=&#8221;software-tools&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_gradient_start=&#8221;#ffffff&#8221; background_color_gradient_end=&#8221;#e5e5e5&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;center_right&#8221; da_popup_slug=&#8221;software-tools&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Row&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_direction=&#8221;bottom&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/exagon_series_label.png&#8221; alt=&#8221;Exagon Series&#8221; title_text=&#8221;Exagon Series&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Strumenti Software<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Spot&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Programmi di Avvio Rapido (presenti in tutte le configurazioni)<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/blurb_fast_start.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;iMRS prime&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Imrs Prime ti permette di iniziare subito! Tutti i programmi di Avvio Rapido sono progettati per la facilit\u00e0 d\u2019uso, rendendo le applicazioni olistiche molto semplici e altamente efficaci con un uso quotidiano. Tutti i programmi di Avvio Rapido sono automaticamente allineati e sincronizzati con Exagon Brain, durante il funzionamento!<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;230682,230679,230676,230673,230670,230667,230664,235619,235611&#8243; posts_number=&#8221;7&#8243; show_title_and_caption=&#8221;off&#8221; show_pagination=&#8221;off&#8221; zoom_icon_color=&#8221;RGBA(255,255,255,0)&#8221; hover_overlay_color=&#8221;RGBA(255,255,255,0)&#8221; module_class=&#8221;col-width fast-start-icons&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Spot&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Modalit\u00e0 manuale<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/blurb_manual_modepng.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;iMRS prime&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Modalit\u00e0 base di applicazione. Imposta manualmente tutti i parametri, basandoti sulle indicazioni fornite dal tuo consulente LifeStyle SwissBionic.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Spot&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Programmi personalizzati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/blurb_user.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;iMRS prime&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Imrs Prime ti consente di preprogrammare pi\u00f9 utenti con tutti i parametri e gli accessori e salvarli nella sezione \u201carchiviazione\u201d del pannello di controllo.<\/p>\n<p>Ogni volta che l\u2019utente designato desidera eseguire un\u2019applicazione, \u00e8 sufficiente scegliere l\u2019accesorio e il sistema fornir\u00e0 i parametri predefiniti!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Exagon Spot&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Funzione Divisa \u201cSplit Mode\u201d<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/blurb_split.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;iMRS prime&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Due sistemi PEMF in UNO!<\/strong><\/p>\n<p>iMRS prime \u00e8 il primo sistema PEMF al mondo che consente due applicazioni indipendenti con una sola unit\u00e0 di controllo! La connector box di IMRS prime \u00e8 dotato di 6 ingressi per applicatori (3 su ogni lato) e contiene 2 convertitori D\/A ugualmente alimentati. Lo \u201cSplit Mode\u201d divide il touchscreen in due parti di funzionamento autonome che consentono di impostare parametri e applicatori indipendenti per ogni sessione.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;iMRS prime Accessories 01&#8243; module_id=&#8221;imrs_prime_accessories&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_enable_mask_style=&#8221;on&#8221; background_mask_style=&#8221;corner-square&#8221; background_mask_color=&#8221;#22A2FF&#8221; background_mask_transform=&#8221;invert&#8221; da_popup_slug=&#8221;imrs_prime_accessories&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Row&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_direction=&#8221;bottom&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/logo_imrs_prime.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;iMRS prime&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>iMRS prime Accessori<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;iMRS prime Accessories 02&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Copertura morbida di cotone per Exagon Mat<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-cotton-flex-cover.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;imrs-prime-cotton-flex-cover&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Copertura in cotone elastico per OmniMat. Rimovibile e lavabile<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Accessories 03&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Borsa per unit\u00e0 di controllo iMRS prime<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-bag-control-unit.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;imrs-prime-bag-control-unit&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Borsa piccolo per l\u2019unit\u00e0 di controllo, batteria e altri accessori.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Accessories 04&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Borsa da trasporto per accessori Exagon<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-bag-applicators.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;imrs-prime-bag-applicators&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Borsa da trasporto per tutti gli applicatori Exagon (Exagon Mat\/FIR, Exagon Pad, Exagon Spot).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Accessories 05&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>iMRs prime Carefree plus 12 mesi<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-carefree-12-1.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;imrs-prime-carefree-12&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Estensione di garanzia iMRS prime a 12 mesi, che include sostituzioni senza limiti nel caso di difetti tecnici all\u2019interno del periodo di garanzia selezionato.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Accessories 06&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>iMRs prime Carefree plus 24 mesi<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-carefree-24-1.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;imrs-prime-carefree-24&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Estensione di garanzia iMRS prime a 24 mesi, che include sostituzioni senza limiti nel caso di difetti tecnici all\u2019interno del periodo di garanzia selezionato.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;iMRS prime Accessories 07&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>iMRS prime pacchetto servizio completo<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs-prime-expert-advanced.png&#8221; alt=&#8221;iMRS prime&#8221; title_text=&#8221;imrs-prime-expert-advanced&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul class=\"list-imrs-prime  dark-line\">\n<li>Una volta consegnato il Sistema iMRS prime, il cliente riceve una chiamata zoom ini- ziale durante la quale un nostro tecnico Prime Tech seguir\u00e0 l\u2019installazione e attiva- zione del Sistema.<\/li>\n<li>12 mesi di assistenza risoluzione problemi direttamente via mail con un tecnico Prime Tech assegnato.<\/li>\n<li>Risoluzione problem tecnici entro 48 ore.<\/li>\n<li>In caso sia necessario segnalare un problema tecnico, il tecnico Prime Tech creer\u00e0 il \u201cSupport Ticket\u201d per il cliente.<\/li>\n<li>Estensione di garanzia iMRS prime di 12 mesi.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#22A2FF&#8221; top_divider_height=&#8221;60px&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrs_prime_brochure_en.png&#8221; alt=&#8221;iMRS prime Bruchure english&#8221; title_text=&#8221;iMRS prime Bruchure english&#8221; url=&#8221;https:\/\/backoffice.swissbionic.com\/documents\/flyer\/imrs_prime\/brochure_imrs_prime_it.pdf&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_text_align_tablet=&#8221;center&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Opuscolo iMRS prime<\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/backoffice.swissbionic.com\/documents\/flyer\/imrs_prime\/brochure_imrs_prime_it.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Scarica qui&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#22A2FF&#8221; button_bg_color=&#8221;#FFFFFF&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;3px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Manuals&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#efefef&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Istruzioni per l&#8217;uso<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>iMRS prime<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/bedienungsanleitung_imrs_prime_en_PRINT_ifu_01_240521.pdf\" target=\"_blank\" rel=\"noopener\">Inglese (tutto il mondo tranne gli USA)<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/bedienungsanleitung_imrs_prime_us_PRINT_ifu_01_202103.pdf\" target=\"_blank\" rel=\"noopener\">Inglese (USA)<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/bedienungsanleitung_imrs_prime_de_ifu_01_202401.pdf\" target=\"_blank\" rel=\"noopener\">Tedesco<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2021\/Istruzioni_per_l_uso_imrs_prime_it.pdf\" target=\"_blank\" rel=\"noopener\">Italian<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2021\/Instructions%20d%E2%80%98utilisation_imrs_prime_fr.pdf\" target=\"_blank\" rel=\"noopener\">Francese<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/bedienungsanleitung_imrs_prime_es_PRINT_ifu_01_240711.pdf\" target=\"_blank\" rel=\"noopener\">Spagnolo<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Exagon Brain<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2023\/exagon_brain_operating_manual_en_din_2023_08_print.pdf\" target=\"_blank\" rel=\"noopener\">Inglese (formato DIN)<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2023\/exagon_brain_operating_manual_en_letter_2023_08_print.pdf\" target=\"_blank\" rel=\"noopener\">Inglese (formato lettera)<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2023\/exagon_brain_bedienungsanleitung_de_2023_08_print.pdf\" target=\"_blank\" rel=\"noopener\">Tedesco<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2023\/exagon_brain_manuale%20operativo_IT_din_2024_05.pdf\" target=\"_blank\" rel=\"noopener\">Italiano<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2021\/manuel_d_utilisation_ExagonBrain_fr.pdf\" target=\"_blank\" rel=\"noopener\">French<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/exagon_brain_manual_de_operacion_ES_din_2024_07.pdf\" target=\"_blank\" rel=\"noopener\">Spagnolo<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Exagon Sense<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/operating_manual_exagon_sense_DINA5.pdf\" target=\"_blank\" rel=\"noopener\">Inglese<\/a><\/p>\n<p><a href=\"https:\/\/backoffice.swissbionic.com\/documents\/manuals2024\/bedienungsanleitung_exagon_sense_DINA5_DE.pdf\" target=\"_blank\" rel=\"noopener\">Tedesco<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;POPUP&#8221; module_class=&#8221;lightbox-content-bluecta&#8221; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;Contact form&#8221; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f233335-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/233463#wpcf7-f233335-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"233335\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f233335-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:233335,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:&quot;400&quot;,&quot;animation_outtime&quot;:&quot;400&quot;,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:&quot;&quot;,&quot;notice_dismissed_rollback-cf7-5.5.6&quot;:true,&quot;notice_dismissed_rollback-cf7-5.7.4&quot;:true,&quot;notice_dismissed_update-cf7-5.8.7&quot;:true,&quot;notice_dismissed_update-cf7-5.9.3&quot;:true,&quot;notice_dismissed_update-cf7-6.1&quot;:true,&quot;notice_dismissed_update-cf7-6.1.5&quot;:true}}\" \/>\n<\/div>\n<div class=\"wps-form\">\n\t<p><strong>Please enter your address and contact information in the form. Your sales partner <span id=\"rep_choice-2\"><\/span> will get in touch with you.<\/strong>\n\t<\/p>\n\t<p><label>Your name<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Name\" \/><\/span><br \/>\n<span id=\"wpcf7-6a572bd0ea9f3-wrapper\" class=\"wpcf7-form-control-wrap name3-wrap\" ><label for=\"name3\" class=\"hp-message\">Name 3<\/label><input id=\"name3\"  placeholder=\"Name 3\"  class=\"wpcf7-form-control wpcf7-text name3\" type=\"text\" name=\"name3\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"off\" \/><\/span>\n\t<\/p>\n\t<div class=\"wps-form-row\">\n\t\t<div class=\"wps-form-column wps-form-column-1\">\n\t\t\t<p><label>Street<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Street\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Street\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"wps-form-column wps-form-column-2\">\n\t\t\t<p><label>Country<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Country\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wps-form-row\">\n\t\t<div class=\"wps-form-column wps-form-column-1\">\n\t\t\t<p><label>ZIP\/Postal<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"zip\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"zip\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"wps-form-column wps-form-column-2\">\n\t\t\t<p><label>City\/Town<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"city\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wps-form-row\">\n\t\t<div class=\"wps-form-column wps-form-column-1\">\n\t\t\t<p><label>Your email<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"wps-form-column wps-form-column-2\">\n\t\t\t<p><label>Your phone number<span class=\"form-required\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<p><label>Product<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"product\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"product_choice\" readonly=\"readonly\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"product\" \/><\/span>\n\t<\/p>\n\t<p><label>Your Contact Person<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"ContactPerson\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"rep_choice\" readonly=\"readonly\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"ContactPerson\" \/><\/span>\n\t<\/p>\n\t<div style=\"display: none;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ContactPersonId\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"repid_choice\" readonly=\"readonly\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"ContactPersonId\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<p>Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span>\n\t<\/p>\n\t<div class=\"wps-form-acceptance\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"bestaetigung\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"bestaetigung\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> By submitting this form, you confirm that you have read and accepted the <a href=\"\/datenschutz\" target=\"_blank\">Privacy Policy<\/a><span class=\"form-required\">*<\/span>.\n\t\t<\/p>\n\t<\/div>\n\t<p><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"antispam-math\"><label><span class=\"wpcf7-quiz-label\">Spam protection: 7+3?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"antispam-math\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_antispam-math\" value=\"fd735f4b4104c2b5e757b922495cb4f6\" \/><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n\t<\/p>\n\t<div class=\"wps-form-hint\">\n\t\t<p>Please fill in all feilds marked with an <span class=\"form-required\">*<\/span> so we can offer you the best possible service.\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019unico e il solo sistema CEMP-6D per il benessere!\t<div class=\"wrap_svl_center\">\r\n\t<div class=\"wrap_svl_center_box\">\r\n\t<div class=\"wrap_svl\" id=\"body_drag_234848\">\r\n\t\t<div class=\"images_wrap\">\r\n                            <img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/imrsprime-expert-set.png\" alt=\"\">\r\n            \t\t<\/div>\t\r\n\t\t \t\t \t\t <div class=\"drag_element tips \" style=\"top:45.58%;left:66.22%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Brain&lt;\/h4&gt;\n&lt;p&gt;Sincronizzatore delle onde cerebrali &#8211; Terapia olistica per il cervello umano!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-7&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:22.37%;left:50.55%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;iMRS prime Unit\u00e0 di controllo&lt;\/h4&gt;\n&lt;p&gt;Schermo LCD touch screen capacitivo da 10.2 pollici.&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-1&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n&lt;h4&gt;iMRS prime Strumenti Software&lt;\/h4&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#software-tools&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:27.38%;left:21%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Applicatore Spot&lt;\/h4&gt;\n&lt;p&gt;L\u2019applicatore specifico per trattare piccole aree del corpo&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-5&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:12.52%;left:28.56%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Applicatore Pad&lt;\/h4&gt;\n&lt;p&gt;L\u2019applicatore locale da utilizzare su aree specifiche del corpo!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-4&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:66.11%;left:43.78%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Sense&lt;\/h4&gt;\n&lt;p&gt;Tencologia Biofeedback&lt;br \/&gt;\nMonitora \u2013 Analizza \u2013 Valuta!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-8&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:67.45%;left:72%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;Exagon Applicatore FIR&lt;\/h4&gt;\n&lt;p&gt;Il primo e unico applicatore-ibrido al mondo!&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-3&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:44.24%;left:38.44%;\" >\r\n\t\t \t<div class=\"point_style has-hover ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;\r\n\t\t\t\t\t&lt;span class=&quot;close_ihp&quot;&gt;\r\n\t\t\t\t\t\t&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;\r\n\t\t\t\t\t\t&lt;h4&gt;iMRS prime Connector Box&lt;\/h4&gt;\n&lt;p&gt;Elemento progettato come collegamento tra l\u2019unit\u00e0 di controllo iMRS prime e gli applicatori\/accessori.&lt;\/p&gt;\n&lt;p&gt;&lt;a class=&quot;et_pb_button button_blue&quot; href=&quot;#section-2&quot;&gt;Per saperne di pi\u00f9&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&nbsp;&lt;\/p&gt;\n\t\t\t\t\t&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-20px;left:-20px;height:40px;width:40px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_1.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-20px;left:-20px\" alt=\"\">\r\n\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/www.swissbionic.com\/wp-content\/uploads\/pin_2.png\" class=\"pins_image_hover ihotspot_hastooltop\"  style=\"top:-20px;left:-20px\" alt=\"\">\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t \r\n\t\t  \t\t \t\r\n\t <\/div>\r\n\t <\/div>\r\n\t <\/div>\r\n\tUnit\u00e0 di controllo Struttura e piedistallo in alluminio spazzolato, ROHS\/REACH\/IP20. Schermo LCD touch screen capacitivo da 10.2 pollici. 2 ingressi audio (3.5). 2 ingressi USB. Cavo di collegamento (20-pin) alla Connector box. LED Indicatore di potenza. 2 Altoparlanti integrati. Sensore NFC. Chiudere la galleriaiMRS prime Connector [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/pages\/233463"}],"collection":[{"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/comments?post=233463"}],"version-history":[{"count":2,"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/pages\/233463\/revisions"}],"predecessor-version":[{"id":237515,"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/pages\/233463\/revisions\/237515"}],"wp:attachment":[{"href":"https:\/\/recoveru.swissbionic.com\/it\/wp-json\/wp\/v2\/media?parent=233463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}